{"id":604969310,"count":1,"description":"","link":"https:\/\/superior-english.com\/en\/tag\/unterschiede-usa-deutschland\/","name":"unterschiede USA Deutschland","slug":"unterschiede-usa-deutschland","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/superior-english.com\/en\/wp-json\/wp\/v2\/tags\/604969310","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/superior-english.com\/en\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/superior-english.com\/en\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/superior-english.com\/en\/wp-json\/wp\/v2\/posts?tags=604969310"},{"href":"https:\/\/superior-english.com\/en\/wp-json\/wp\/v2\/pages?tags=604969310"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}